{"id":1,"name":"Jasonxue","url":"https:\/\/kabrasives.com","description":"","link":"https:\/\/kabrasives.com\/bn\/blog\/author\/Jasonxue\/","slug":"Jasonxue","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8a9bdb892d57e70c0de6902869137644fd47304144ff8732d63e81ee5b572348?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8a9bdb892d57e70c0de6902869137644fd47304144ff8732d63e81ee5b572348?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8a9bdb892d57e70c0de6902869137644fd47304144ff8732d63e81ee5b572348?s=96&d=mm&r=g"},"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.4 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Jasonxue, Author at Kangfeides<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kabrasives.com\/bn\/blog\/author\/Jasonxue\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"profile\" \/>\n<meta property=\"og:title\" content=\"Jasonxue\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kabrasives.com\/bn\/blog\/author\/Jasonxue\/\" \/>\n<meta property=\"og:site_name\" content=\"Kangfeides\" \/>\n<meta property=\"og:image\" content=\"https:\/\/secure.gravatar.com\/avatar\/e25f8c0ee9e811ab9387494b3dc22145?s=500&d=mm&r=g\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"ProfilePage\",\"@id\":\"https:\\\/\\\/kabrasives.com\\\/blog\\\/author\\\/Jasonxue\\\/\",\"url\":\"https:\\\/\\\/kabrasives.com\\\/blog\\\/author\\\/Jasonxue\\\/\",\"name\":\"Jasonxue, Author at Kangfeides\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kabrasives.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kabrasives.com\\\/blog\\\/author\\\/Jasonxue\\\/#breadcrumb\"},\"inLanguage\":\"bn-BD\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kabrasives.com\\\/blog\\\/author\\\/Jasonxue\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kabrasives.com\\\/blog\\\/author\\\/Jasonxue\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kabrasives.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Archives for Jasonxue\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kabrasives.com\\\/#website\",\"url\":\"https:\\\/\\\/kabrasives.com\\\/\",\"name\":\"Kangfeides\",\"description\":\"China&#039;s top Steel Shot Supplier\",\"publisher\":{\"@id\":\"https:\\\/\\\/kabrasives.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kabrasives.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"bn-BD\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kabrasives.com\\\/#organization\",\"name\":\"Kangfeides\",\"url\":\"https:\\\/\\\/kabrasives.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"bn-BD\",\"@id\":\"https:\\\/\\\/kabrasives.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kabrasives.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/3-2.png\",\"contentUrl\":\"https:\\\/\\\/kabrasives.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/3-2.png\",\"width\":512,\"height\":512,\"caption\":\"Kangfeides\"},\"image\":{\"@id\":\"https:\\\/\\\/kabrasives.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kabrasives.com\\\/#\\\/schema\\\/person\\\/acd9c450ce51bc53e9d3775286e30d17\",\"name\":\"Jasonxue\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"bn-BD\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a9bdb892d57e70c0de6902869137644fd47304144ff8732d63e81ee5b572348?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a9bdb892d57e70c0de6902869137644fd47304144ff8732d63e81ee5b572348?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a9bdb892d57e70c0de6902869137644fd47304144ff8732d63e81ee5b572348?s=96&d=mm&r=g\",\"caption\":\"Jasonxue\"},\"sameAs\":[\"https:\\\/\\\/kabrasives.com\"],\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kabrasives.com\\\/blog\\\/author\\\/Jasonxue\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Jasonxue, Author at Kangfeides","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kabrasives.com\/bn\/blog\/author\/Jasonxue\/","og_locale":"en_US","og_type":"profile","og_title":"Jasonxue","og_url":"https:\/\/kabrasives.com\/bn\/blog\/author\/Jasonxue\/","og_site_name":"Kangfeides","og_image":[{"url":"https:\/\/secure.gravatar.com\/avatar\/e25f8c0ee9e811ab9387494b3dc22145?s=500&d=mm&r=g","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ProfilePage","@id":"https:\/\/kabrasives.com\/blog\/author\/Jasonxue\/","url":"https:\/\/kabrasives.com\/blog\/author\/Jasonxue\/","name":"Jasonxue, Author at Kangfeides","isPartOf":{"@id":"https:\/\/kabrasives.com\/#website"},"breadcrumb":{"@id":"https:\/\/kabrasives.com\/blog\/author\/Jasonxue\/#breadcrumb"},"inLanguage":"bn-BD","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kabrasives.com\/blog\/author\/Jasonxue\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kabrasives.com\/blog\/author\/Jasonxue\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kabrasives.com\/"},{"@type":"ListItem","position":2,"name":"Archives for Jasonxue"}]},{"@type":"WebSite","@id":"https:\/\/kabrasives.com\/#website","url":"https:\/\/kabrasives.com\/","name":"Kangfeides","description":"China&#039;s top Steel Shot Supplier","publisher":{"@id":"https:\/\/kabrasives.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kabrasives.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"bn-BD"},{"@type":"Organization","@id":"https:\/\/kabrasives.com\/#organization","name":"Kangfeides","url":"https:\/\/kabrasives.com\/","logo":{"@type":"ImageObject","inLanguage":"bn-BD","@id":"https:\/\/kabrasives.com\/#\/schema\/logo\/image\/","url":"https:\/\/kabrasives.com\/wp-content\/uploads\/2023\/10\/3-2.png","contentUrl":"https:\/\/kabrasives.com\/wp-content\/uploads\/2023\/10\/3-2.png","width":512,"height":512,"caption":"Kangfeides"},"image":{"@id":"https:\/\/kabrasives.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/kabrasives.com\/#\/schema\/person\/acd9c450ce51bc53e9d3775286e30d17","name":"Jasonxue","image":{"@type":"ImageObject","inLanguage":"bn-BD","@id":"https:\/\/secure.gravatar.com\/avatar\/8a9bdb892d57e70c0de6902869137644fd47304144ff8732d63e81ee5b572348?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a9bdb892d57e70c0de6902869137644fd47304144ff8732d63e81ee5b572348?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a9bdb892d57e70c0de6902869137644fd47304144ff8732d63e81ee5b572348?s=96&d=mm&r=g","caption":"Jasonxue"},"sameAs":["https:\/\/kabrasives.com"],"mainEntityOfPage":{"@id":"https:\/\/kabrasives.com\/blog\/author\/Jasonxue\/"}}]}},"elementor_introduction":{"ai-get-started-announcement":true,"globals_introduction":true,"exit_to":true,"yoast-introduction":true,"e-editor-one-notice-pointer":true},"_links":{"self":[{"href":"https:\/\/kabrasives.com\/bn\/wp-json\/wp\/v2\/users\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kabrasives.com\/bn\/wp-json\/wp\/v2\/users"}]}}